{"id":1407,"count":1,"description":"","link":"https:\/\/rikversteeg.com\/nl\/tag\/donatie\/","name":"donatie","slug":"donatie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>donatie Archives - Studio Rik Versteeg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rikversteeg.com\/nl\/tag\/donatie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"donatie Archives - Studio Rik Versteeg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rikversteeg.com\/nl\/tag\/donatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Rik Versteeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/tag\\\/donatie\\\/\",\"url\":\"https:\\\/\\\/rikversteeg.com\\\/tag\\\/donatie\\\/\",\"name\":\"donatie Archives - Studio Rik Versteeg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/tag\\\/donatie\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/tag\\\/donatie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rikversteeg.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"donatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/#website\",\"url\":\"https:\\\/\\\/rikversteeg.com\\\/\",\"name\":\"Studio Rik Versteeg\",\"description\":\"Visual Artist, Rotterdam. Photography, Film, Design and Make-up. Fine Art Prints\",\"publisher\":{\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/#\\\/schema\\\/person\\\/78d0b18f065861b29ce513f7b1dfbf88\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rikversteeg.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/#\\\/schema\\\/person\\\/78d0b18f065861b29ce513f7b1dfbf88\",\"name\":\"Rik Versteeg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logorv.png\",\"url\":\"https:\\\/\\\/rikversteeg.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logorv.png\",\"contentUrl\":\"https:\\\/\\\/rikversteeg.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logorv.png\",\"width\":400,\"height\":400,\"caption\":\"Rik Versteeg\"},\"logo\":{\"@id\":\"https:\\\/\\\/rikversteeg.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logorv.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"donatie Archives - Studio Rik Versteeg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rikversteeg.com\/nl\/tag\/donatie\/","og_locale":"nl_NL","og_type":"article","og_title":"donatie Archives - Studio Rik Versteeg","og_url":"https:\/\/rikversteeg.com\/nl\/tag\/donatie\/","og_site_name":"Studio Rik Versteeg","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rikversteeg.com\/tag\/donatie\/","url":"https:\/\/rikversteeg.com\/tag\/donatie\/","name":"donatie Archives - Studio Rik Versteeg","isPartOf":{"@id":"https:\/\/rikversteeg.com\/#website"},"breadcrumb":{"@id":"https:\/\/rikversteeg.com\/tag\/donatie\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/rikversteeg.com\/tag\/donatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rikversteeg.com\/"},{"@type":"ListItem","position":2,"name":"donatie"}]},{"@type":"WebSite","@id":"https:\/\/rikversteeg.com\/#website","url":"https:\/\/rikversteeg.com\/","name":"Studio Rik Versteeg","description":"Visual Artist, Rotterdam. Photography, Film, Design and Make-up. Fine Art Prints","publisher":{"@id":"https:\/\/rikversteeg.com\/#\/schema\/person\/78d0b18f065861b29ce513f7b1dfbf88"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rikversteeg.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Person","Organization"],"@id":"https:\/\/rikversteeg.com\/#\/schema\/person\/78d0b18f065861b29ce513f7b1dfbf88","name":"Rik Versteeg","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/rikversteeg.com\/wp-content\/uploads\/2024\/02\/logorv.png","url":"https:\/\/rikversteeg.com\/wp-content\/uploads\/2024\/02\/logorv.png","contentUrl":"https:\/\/rikversteeg.com\/wp-content\/uploads\/2024\/02\/logorv.png","width":400,"height":400,"caption":"Rik Versteeg"},"logo":{"@id":"https:\/\/rikversteeg.com\/wp-content\/uploads\/2024\/02\/logorv.png"}}]}},"_links":{"self":[{"href":"https:\/\/rikversteeg.com\/nl\/wp-json\/wp\/v2\/tags\/1407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rikversteeg.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rikversteeg.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rikversteeg.com\/nl\/wp-json\/wp\/v2\/posts?tags=1407"},{"href":"https:\/\/rikversteeg.com\/nl\/wp-json\/wp\/v2\/pages?tags=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}